{"id":95852,"date":"2026-03-25T04:43:31","date_gmt":"2026-03-25T04:43:31","guid":{"rendered":"https:\/\/www.jalonzeolite.com\/?post_type=news_events&#038;p=95852"},"modified":"2026-04-23T02:01:38","modified_gmt":"2026-04-23T02:01:38","slug":"jalon-named-platinum-sponsor-at-the-sustainable-aviation-fuels-summit-2026","status":"publish","type":"news_events","link":"https:\/\/www.jalonzeolite.com\/pt\/news_events\/jalon-named-platinum-sponsor-at-the-sustainable-aviation-fuels-summit-2026\/","title":{"rendered":"A JALON foi nomeada Patrocinador de Platina na Cimeira de Combust\u00edveis para a Avia\u00e7\u00e3o Sustent\u00e1vel 2026"},"content":{"rendered":"<p>A JALON foi nomeada Patrocinador de Platina na Cimeira de Combust\u00edveis para a Avia\u00e7\u00e3o Sustent\u00e1vel 2026, destacando o seu compromisso cont\u00ednuo em apoiar o desenvolvimento de combust\u00edveis para a avia\u00e7\u00e3o sustent\u00e1veis e solu\u00e7\u00f5es energ\u00e9ticas de baixo carbono mais amplas.<\/p>\n\n\n\n<p>\u00c0 medida que o impulso global para a energia com baixo teor de carbono continua a ganhar \u00edmpeto, a procura de tecnologias de combust\u00edvel sustent\u00e1vel eficientes e fi\u00e1veis est\u00e1 a crescer rapidamente. Da avia\u00e7\u00e3o \u00e0 moderniza\u00e7\u00e3o do g\u00e1s e \u00e0 produ\u00e7\u00e3o de biocombust\u00edveis, a melhoria do desempenho dos processos tornou-se uma prioridade fundamental em todo o sector da energia.<\/p>\n\n\n\n<p>A JALON, um dos principais fornecedores mundiais de adsorventes de peneiras moleculares e materiais catalisadores, apoia uma vasta gama de aplica\u00e7\u00f5es energ\u00e9ticas e qu\u00edmicas atrav\u00e9s de engenharia avan\u00e7ada de materiais e solu\u00e7\u00f5es de processos integrados. No sector da bioenergia, as tecnologias da JALON s\u00e3o aplicadas em \u00e1reas-chave, incluindo a produ\u00e7\u00e3o sustent\u00e1vel de combust\u00edvel para a avia\u00e7\u00e3o, o melhoramento do biog\u00e1s e a desidrata\u00e7\u00e3o do etanol combust\u00edvel.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conecte-se com a JALON no estande n\u00ba 4<\/strong><\/h2>\n\n\n\n<p>Se estiver presente na Cimeira de Combust\u00edveis para a Avia\u00e7\u00e3o Sustent\u00e1vel 2026, visite a nossa equipa no stand n.\u00ba 4 para discutir os seus projectos e explorar solu\u00e7\u00f5es pr\u00e1ticas para a produ\u00e7\u00e3o de combust\u00edvel sustent\u00e1vel.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"505\" height=\"446\" src=\"https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/Floor-Plan-Biofuel.png\" alt=\"\" class=\"wp-image-95914\" style=\"width:505px;height:auto\" srcset=\"https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/Floor-Plan-Biofuel.png 505w, https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/Floor-Plan-Biofuel-14x12.png 14w\" sizes=\"(max-width: 505px) 100vw, 505px\" \/><\/figure><\/div>\n\n\n<p><strong>Detalhes do stand:<\/strong>&nbsp;NO. 4 <br><strong>Pessoa de contacto 1:<\/strong>&nbsp;Amber Feng   <strong>Tel\/WhatsApp\/WeChat:<\/strong>&nbsp;+86 138 3799 6116<br><strong>Pessoa de contacto 2:<\/strong>&nbsp;Jack Zhang     <strong>Tel\/WhatsApp\/WeChat:<\/strong>&nbsp;+86 137 0079 0205<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Apoiar a produ\u00e7\u00e3o de SAF atrav\u00e9s de cat\u00e1lise avan\u00e7ada<\/strong><\/h2>\n\n\n\n<p>O Combust\u00edvel de Avia\u00e7\u00e3o Sustent\u00e1vel (SAF) \u00e9 amplamente reconhecido como uma das formas mais eficazes de reduzir as emiss\u00f5es na ind\u00fastria da avia\u00e7\u00e3o. Entre as vias de produ\u00e7\u00e3o dispon\u00edveis, a via HEFA-SPK continua a ser a mais madura e amplamente adoptada \u00e0 escala industrial.<\/p>\n\n\n\n<p>Dentro deste processo, a fase de isomeriza\u00e7\u00e3o desempenha um papel cr\u00edtico na determina\u00e7\u00e3o da qualidade do combust\u00edvel. As solu\u00e7\u00f5es de catalisadores da JALON s\u00e3o concebidas para suportar um funcionamento est\u00e1vel, permitindo a convers\u00e3o de parafinas de cadeia longa em hidrocarbonetos ramificados com propriedades melhoradas a baixa temperatura.<\/p>\n\n\n\n<p>Ao ajudar a manter a qualidade do produto, limitando as reac\u00e7\u00f5es secund\u00e1rias indesejadas, estas solu\u00e7\u00f5es apoiam a produ\u00e7\u00e3o eficiente de SAF que cumpre as especifica\u00e7\u00f5es internacionais, como a ASTM D7566.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Melhorar a valoriza\u00e7\u00e3o do biog\u00e1s para a produ\u00e7\u00e3o de biometano<\/strong><\/h2>\n\n\n\n<p>O melhoramento do biog\u00e1s \u00e9 outra via importante na transi\u00e7\u00e3o para as energias renov\u00e1veis. A convers\u00e3o de biog\u00e1s bruto em biometano de elevada pureza requer um desempenho de separa\u00e7\u00e3o fi\u00e1vel e um funcionamento est\u00e1vel a longo prazo.<\/p>\n\n\n\n<p>A JALON fornece materiais de adsor\u00e7\u00e3o e suporte de processo para sistemas VPSA utilizados na produ\u00e7\u00e3o de biometano e g\u00e1s natural renov\u00e1vel (RNG).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"603\" height=\"449\" src=\"https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image.png\" alt=\"\" class=\"wp-image-95915\" style=\"width:629px;height:auto\" srcset=\"https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image.png 603w, https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image-16x12.png 16w, https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image-600x447.png 600w\" sizes=\"(max-width: 603px) 100vw, 603px\" \/><\/figure><\/div>\n\n\n<p>Em compara\u00e7\u00e3o com os materiais adsorventes VPSA convencionais, as solu\u00e7\u00f5es da JALON ajudam a reduzir a carga de adsorvente, melhoram a recupera\u00e7\u00e3o de metano e reduzem o consumo de energia operacional da unidade. Isto contribui para uma maior efici\u00eancia do processo e um melhor desempenho global da f\u00e1brica.<\/p>\n\n\n\n<p>Al\u00e9m disso, a JALON trabalha com parceiros tecnol\u00f3gicos para apoiar sistemas de moderniza\u00e7\u00e3o modulares e montados em skids, oferecendo solu\u00e7\u00f5es flex\u00edveis para projectos com diferentes capacidades e requisitos de instala\u00e7\u00e3o.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solu\u00e7\u00f5es confi\u00e1veis de peneira molecular para desidrata\u00e7\u00e3o de etanol<\/strong><\/h2>\n\n\n\n<p>Na produ\u00e7\u00e3o de etanol combust\u00edvel, a desidrata\u00e7\u00e3o por peneira molecular continua a ser a tecnologia padr\u00e3o para obter etanol anidro.<\/p>\n\n\n\n<p>Os adsorventes de peneira molecular da JALON s\u00e3o projetados para aplica\u00e7\u00f5es de desidrata\u00e7\u00e3o de etanol, oferecendo desempenho est\u00e1vel em condi\u00e7\u00f5es de opera\u00e7\u00e3o industrial.<\/p>\n\n\n\n<p>Com elevada efici\u00eancia de adsor\u00e7\u00e3o, forte estabilidade mec\u00e2nica e baixa produ\u00e7\u00e3o de poeiras, estes materiais ajudam a reduzir a queda de press\u00e3o, a minimizar o desgaste do equipamento e a prolongar a vida \u00fatil do adsorvente.<\/p>\n\n\n\n<p>Isto permite aos produtores de etanol manter um funcionamento est\u00e1vel a longo prazo, reduzindo simultaneamente os requisitos de manuten\u00e7\u00e3o e os custos de funcionamento.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Apoiar o crescimento dos combust\u00edveis sustent\u00e1veis<\/strong><\/strong><\/h2>\n\n\n\n<p>\u00c0 medida que o sistema energ\u00e9tico global continua a evoluir, os combust\u00edveis renov\u00e1veis, como o SAF, o biometano e o bioetanol, desempenhar\u00e3o um papel cada vez mais importante na redu\u00e7\u00e3o das emiss\u00f5es nos sectores dos transportes e da energia. Ao combinar materiais avan\u00e7ados de adsor\u00e7\u00e3o e cat\u00e1lise e solu\u00e7\u00f5es de processo integradas, a JALON tem como objetivo apoiar o desenvolvimento cont\u00ednuo e a implanta\u00e7\u00e3o em larga escala de tecnologias de produ\u00e7\u00e3o de energia sustent\u00e1vel em todo o mundo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"557\" height=\"301\" src=\"https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image-1.png\" alt=\"\" class=\"wp-image-95916\" style=\"width:807px;height:auto\" srcset=\"https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image-1.png 557w, https:\/\/www.jalonzeolite.com\/wp-content\/uploads\/2026\/03\/image-1-18x10.png 18w\" sizes=\"(max-width: 557px) 100vw, 557px\" \/><\/figure>\n\n\n\n<p>A JALON d\u00e1 as boas-vindas aos profissionais da ind\u00fastria para se encontrarem com a equipa no stand n\u00ba 4 durante a Cimeira de Combust\u00edveis para a Avia\u00e7\u00e3o Sustent\u00e1vel 2026. Os nossos especialistas t\u00e9cnicos estar\u00e3o dispon\u00edveis para discutir os requisitos do seu projeto, partilhar experi\u00eancias de aplica\u00e7\u00e3o e explorar como as solu\u00e7\u00f5es de adsor\u00e7\u00e3o e cat\u00e1lise da JALON podem apoiar a sua produ\u00e7\u00e3o de combust\u00edvel sustent\u00e1vel.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>A JALON foi nomeada Patrocinador de Platina na Cimeira de Combust\u00edveis para a Avia\u00e7\u00e3o Sustent\u00e1vel 2026, destacando o seu compromisso cont\u00ednuo em apoiar o desenvolvimento de combust\u00edveis para a avia\u00e7\u00e3o sustent\u00e1veis e solu\u00e7\u00f5es energ\u00e9ticas de baixo carbono mais abrangentes. \u00c0 medida que o impulso global para a energia com baixo teor de carbono continua a ganhar \u00edmpeto, a procura de tecnologias de combust\u00edvel sustent\u00e1vel eficientes e fi\u00e1veis est\u00e1 a crescer rapidamente. Desde a avia\u00e7\u00e3o [...]<\/p>","protected":false},"featured_media":95913,"parent":0,"menu_order":40,"template":"templates\/p066-news-detail.php","class_list":["post-95852","news_events","type-news_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.jalonzeolite.com\/pt\/wp-json\/wp\/v2\/news_events\/95852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jalonzeolite.com\/pt\/wp-json\/wp\/v2\/news_events"}],"about":[{"href":"https:\/\/www.jalonzeolite.com\/pt\/wp-json\/wp\/v2\/types\/news_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jalonzeolite.com\/pt\/wp-json\/wp\/v2\/media\/95913"}],"wp:attachment":[{"href":"https:\/\/www.jalonzeolite.com\/pt\/wp-json\/wp\/v2\/media?parent=95852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}